{"id":1235,"count":1,"description":"","link":"https:\/\/www.alfalon.com.br\/blog\/tag\/rolo-de-teflon-serve-para-gas\/","name":"rolo de teflon serve para g\u00e1s?","slug":"rolo-de-teflon-serve-para-gas","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de rolo de teflon serve para g\u00e1s? - Alfalon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alfalon.com.br\/blog\/tag\/rolo-de-teflon-serve-para-gas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de rolo de teflon serve para g\u00e1s? - Alfalon\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alfalon.com.br\/blog\/tag\/rolo-de-teflon-serve-para-gas\/\" \/>\n<meta property=\"og:site_name\" content=\"Alfalon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.alfalon.com.br\\\/blog\\\/tag\\\/rolo-de-teflon-serve-para-gas\\\/\",\"url\":\"https:\\\/\\\/www.alfalon.com.br\\\/blog\\\/tag\\\/rolo-de-teflon-serve-para-gas\\\/\",\"name\":\"Arquivo de rolo de teflon serve para g\u00e1s? - Alfalon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alfalon.com.br\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alfalon.com.br\\\/blog\\\/tag\\\/rolo-de-teflon-serve-para-gas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alfalon.com.br\\\/blog\\\/tag\\\/rolo-de-teflon-serve-para-gas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.alfalon.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"rolo de teflon serve para g\u00e1s?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alfalon.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.alfalon.com.br\\\/blog\\\/\",\"name\":\"Alfalon\",\"description\":\"com\u00e9rcio e servi\u00e7os pertinentes aos produtos de embalagens\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alfalon.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alfalon.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alfalon.com.br\\\/blog\\\/#organization\",\"name\":\"Alfalon\",\"url\":\"https:\\\/\\\/www.alfalon.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.alfalon.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.alfalon.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-logo-6.png\",\"contentUrl\":\"https:\\\/\\\/www.alfalon.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-logo-6.png\",\"width\":200,\"height\":125,\"caption\":\"Alfalon\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alfalon.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de rolo de teflon serve para g\u00e1s? - Alfalon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alfalon.com.br\/blog\/tag\/rolo-de-teflon-serve-para-gas\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de rolo de teflon serve para g\u00e1s? - Alfalon","og_url":"https:\/\/www.alfalon.com.br\/blog\/tag\/rolo-de-teflon-serve-para-gas\/","og_site_name":"Alfalon","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.alfalon.com.br\/blog\/tag\/rolo-de-teflon-serve-para-gas\/","url":"https:\/\/www.alfalon.com.br\/blog\/tag\/rolo-de-teflon-serve-para-gas\/","name":"Arquivo de rolo de teflon serve para g\u00e1s? - Alfalon","isPartOf":{"@id":"https:\/\/www.alfalon.com.br\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.alfalon.com.br\/blog\/tag\/rolo-de-teflon-serve-para-gas\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.alfalon.com.br\/blog\/tag\/rolo-de-teflon-serve-para-gas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.alfalon.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"rolo de teflon serve para g\u00e1s?"}]},{"@type":"WebSite","@id":"https:\/\/www.alfalon.com.br\/blog\/#website","url":"https:\/\/www.alfalon.com.br\/blog\/","name":"Alfalon","description":"com\u00e9rcio e servi\u00e7os pertinentes aos produtos de embalagens","publisher":{"@id":"https:\/\/www.alfalon.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alfalon.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.alfalon.com.br\/blog\/#organization","name":"Alfalon","url":"https:\/\/www.alfalon.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.alfalon.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.alfalon.com.br\/blog\/wp-content\/uploads\/2024\/04\/cropped-logo-6.png","contentUrl":"https:\/\/www.alfalon.com.br\/blog\/wp-content\/uploads\/2024\/04\/cropped-logo-6.png","width":200,"height":125,"caption":"Alfalon"},"image":{"@id":"https:\/\/www.alfalon.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.alfalon.com.br\/blog\/wp-json\/wp\/v2\/tags\/1235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alfalon.com.br\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.alfalon.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.alfalon.com.br\/blog\/wp-json\/wp\/v2\/posts?tags=1235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}